{"id":276,"date":"2023-12-06T17:15:00","date_gmt":"2023-12-06T16:15:00","guid":{"rendered":"https:\/\/parcsataimes.com\/?p=276"},"modified":"2024-01-26T17:16:23","modified_gmt":"2024-01-26T16:16:23","slug":"coaster-quiz-03-special-noel-1-3","status":"publish","type":"post","link":"https:\/\/parcsataimes.com\/index.php\/2023\/12\/06\/coaster-quiz-03-special-noel-1-3\/","title":{"rendered":"Coaster Quiz &#8211; 03 &#8211; Sp\u00e9cial No\u00ebl 1\/3"},"content":{"rendered":"\n<p>Au programme pour ce 3eme volet, Noel \u00e0 toutes les sauces !<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"P.A.T. &#039; Quiz n\u00b03 - Sp\u00e9cial No\u00ebl ! Testez vos connaissances sur le monde des parcs !\" width=\"1110\" height=\"624\" src=\"https:\/\/www.youtube.com\/embed\/_Dyxi5CWh-o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Au programme pour ce 3eme volet, Noel \u00e0 toutes les sauces !<\/p>\n","protected":false},"author":1,"featured_media":277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","iawp_total_views":0,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-quiz"],"author_meta":{"display_name":"La r\u00e9daction","author_link":"https:\/\/parcsataimes.com\/index.php\/author\/admin1324\/"},"featured_img":"https:\/\/parcsataimes.com\/wp-content\/uploads\/2024\/01\/3-300x169.png","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/parcsataimes.com\/index.php\/category\/nos-quiz\/\" class=\"advgb-post-tax-term\">\u00b7 Coaster Quiz<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">\u00b7 Coaster Quiz<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 3 ans il y a","modified":"Mis \u00e0 jour 2 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 6 d\u00e9cembre 2023","modified":"Mise \u00e0 jour le 26 janvier 2024"},"absolute_dates_time":{"created":"Publi\u00e9 le 6 d\u00e9cembre 2023 17h15","modified":"Mise \u00e0 jour le 26 janvier 2024 17h16"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/posts\/276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":1,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/posts\/276\/revisions"}],"predecessor-version":[{"id":278,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/posts\/276\/revisions\/278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/media\/277"}],"wp:attachment":[{"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/media?parent=276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/categories?post=276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/parcsataimes.com\/index.php\/wp-json\/wp\/v2\/tags?post=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}